{"id":194,"count":7,"description":"","link":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten","name":"Tarten","slug":"tarten","taxonomy":"category","parent":192,"meta":[],"z_taxonomy_image_url":"https:\/\/theblackfig.com\/wp-content\/uploads\/2026\/05\/rezepte-hausgemachte-tarten.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00fc\u00dfe und herzhafte Tarten | The Black Fig<\/title>\n<meta name=\"description\" content=\"Tarten sind eines der typischen Desserts der italienischen K\u00fcche. Es gibt unz\u00e4hlige Varianten: Marmeladentarte, Tarten mit Ricotta, mit Vanillecreme usw.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00fc\u00dfe und herzhafte Tarten | The Black Fig\" \/>\n<meta property=\"og:description\" content=\"Tarten sind eines der typischen Desserts der italienischen K\u00fcche. Es gibt unz\u00e4hlige Varianten: Marmeladentarte, Tarten mit Ricotta, mit Vanillecreme usw.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten\" \/>\n<meta property=\"og:site_name\" content=\"The Black Fig\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theblackfig.com\/wp-content\/uploads\/2019\/08\/theblackfig-FOOD-AND-WINE-ANARCHIST.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de\\\/italienische-gebaeck-rezepte\\\/tarten\",\"url\":\"https:\\\/\\\/theblackfig.com\\\/de\\\/italienische-gebaeck-rezepte\\\/tarten\",\"name\":\"S\u00fc\u00dfe und herzhafte Tarten | The Black Fig\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de#website\"},\"description\":\"Tarten sind eines der typischen Desserts der italienischen K\u00fcche. Es gibt unz\u00e4hlige Varianten: Marmeladentarte, Tarten mit Ricotta, mit Vanillecreme usw.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de\\\/italienische-gebaeck-rezepte\\\/tarten#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de\\\/italienische-gebaeck-rezepte\\\/tarten#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/theblackfig.com\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italienische Geb\u00e4ck-Rezepte\",\"item\":\"https:\\\/\\\/theblackfig.com\\\/de\\\/italienische-gebaeck-rezepte\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tarten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de#website\",\"url\":\"https:\\\/\\\/theblackfig.com\\\/de\",\"name\":\"The Black Fig Food\",\"description\":\"Authentisch italienisch kochen, Italienische Rezepte, Regionale K\u00fcche\",\"publisher\":{\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de#\\\/schema\\\/person\\\/33b5b6cd55d9673fcce068864afa9559\"},\"alternateName\":\"The Black Fig Food\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/theblackfig.com\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/theblackfig.com\\\/de#\\\/schema\\\/person\\\/33b5b6cd55d9673fcce068864afa9559\",\"name\":\"Francesca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/theblackfig.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/vinessum-bw.jpg\",\"url\":\"https:\\\/\\\/theblackfig.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/vinessum-bw.jpg\",\"contentUrl\":\"https:\\\/\\\/theblackfig.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/vinessum-bw.jpg\",\"width\":1178,\"height\":1220,\"caption\":\"Francesca\"},\"logo\":{\"@id\":\"https:\\\/\\\/theblackfig.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/vinessum-bw.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TheBlackFig\\\/\",\"https:\\\/\\\/www.instagram.com\\\/TheBlackFig\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ffantoni\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/theblackfig\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00fc\u00dfe und herzhafte Tarten | The Black Fig","description":"Tarten sind eines der typischen Desserts der italienischen K\u00fcche. Es gibt unz\u00e4hlige Varianten: Marmeladentarte, Tarten mit Ricotta, mit Vanillecreme usw.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten","og_locale":"de_DE","og_type":"article","og_title":"S\u00fc\u00dfe und herzhafte Tarten | The Black Fig","og_description":"Tarten sind eines der typischen Desserts der italienischen K\u00fcche. Es gibt unz\u00e4hlige Varianten: Marmeladentarte, Tarten mit Ricotta, mit Vanillecreme usw.","og_url":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten","og_site_name":"The Black Fig","og_image":[{"width":600,"height":600,"url":"https:\/\/theblackfig.com\/wp-content\/uploads\/2019\/08\/theblackfig-FOOD-AND-WINE-ANARCHIST.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten","url":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten","name":"S\u00fc\u00dfe und herzhafte Tarten | The Black Fig","isPartOf":{"@id":"https:\/\/theblackfig.com\/de#website"},"description":"Tarten sind eines der typischen Desserts der italienischen K\u00fcche. Es gibt unz\u00e4hlige Varianten: Marmeladentarte, Tarten mit Ricotta, mit Vanillecreme usw.","breadcrumb":{"@id":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte\/tarten#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/theblackfig.com\/de"},{"@type":"ListItem","position":2,"name":"Italienische Geb\u00e4ck-Rezepte","item":"https:\/\/theblackfig.com\/de\/italienische-gebaeck-rezepte"},{"@type":"ListItem","position":3,"name":"Tarten"}]},{"@type":"WebSite","@id":"https:\/\/theblackfig.com\/de#website","url":"https:\/\/theblackfig.com\/de","name":"The Black Fig Food","description":"Authentisch italienisch kochen, Italienische Rezepte, Regionale K\u00fcche","publisher":{"@id":"https:\/\/theblackfig.com\/de#\/schema\/person\/33b5b6cd55d9673fcce068864afa9559"},"alternateName":"The Black Fig Food","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theblackfig.com\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/theblackfig.com\/de#\/schema\/person\/33b5b6cd55d9673fcce068864afa9559","name":"Francesca","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/theblackfig.com\/wp-content\/uploads\/2019\/07\/vinessum-bw.jpg","url":"https:\/\/theblackfig.com\/wp-content\/uploads\/2019\/07\/vinessum-bw.jpg","contentUrl":"https:\/\/theblackfig.com\/wp-content\/uploads\/2019\/07\/vinessum-bw.jpg","width":1178,"height":1220,"caption":"Francesca"},"logo":{"@id":"https:\/\/theblackfig.com\/wp-content\/uploads\/2019\/07\/vinessum-bw.jpg"},"sameAs":["https:\/\/www.facebook.com\/TheBlackFig\/","https:\/\/www.instagram.com\/TheBlackFig\/","https:\/\/www.linkedin.com\/in\/ffantoni\/","https:\/\/it.pinterest.com\/theblackfig\/"]}]}},"_links":{"self":[{"href":"https:\/\/theblackfig.com\/de\/wp-json\/wp\/v2\/categories\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theblackfig.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/theblackfig.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/theblackfig.com\/de\/wp-json\/wp\/v2\/categories\/192"}],"wp:post_type":[{"href":"https:\/\/theblackfig.com\/de\/wp-json\/wp\/v2\/posts?categories=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}